{"id":4368,"date":"2020-08-12T16:29:19","date_gmt":"2020-08-12T19:29:19","guid":{"rendered":"https:\/\/meriansrl.com\/home\/?post_type=product&#038;p=4368"},"modified":"2020-08-12T16:39:49","modified_gmt":"2020-08-12T19:39:49","slug":"equipo-plasma-convencional-blucut-60","status":"publish","type":"product","link":"https:\/\/meriansrl.com\/home\/producto\/equipo-plasma-convencional-blucut-60\/","title":{"rendered":"Plasma Convencional BLUCUT 60"},"content":{"rendered":"<p>Aptos para trabajos met\u00e1lica liviana y pesada, mantenimiento, astilleros etc.<br \/>\nModelos Blucut 60 y 80 equipados con torchas neum\u00e1ticas PT80 sin HF. Son adecuados para cualquier trabajo de corte de todos los metales con<br \/>\nexcelente calidad. Modelo Blucut 70 equipado con encendido de acto por alta frecuencia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4369 size-full\" src=\"https:\/\/meriansrl.com\/home\/wp-content\/uploads\/2020\/08\/carc-blu60.png\" alt=\"\" width=\"643\" height=\"363\" srcset=\"https:\/\/meriansrl.com\/home\/wp-content\/uploads\/2020\/08\/carc-blu60.png 643w, https:\/\/meriansrl.com\/home\/wp-content\/uploads\/2020\/08\/carc-blu60-640x361.png 640w, https:\/\/meriansrl.com\/home\/wp-content\/uploads\/2020\/08\/carc-blu60-400x226.png 400w, https:\/\/meriansrl.com\/home\/wp-content\/uploads\/2020\/08\/carc-blu60-600x339.png 600w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equipos de corte por plasma-aire comprimido llevando dos sistemas de seguridad: presostato de aire y termostato de temperatura. R\u00e1pido corte<br \/>\nsin deformar la chapa, incluso pintada, de acero carbono, inoxidable, galvanizada, aluminio, cobre, lat\u00f3n, etc.<\/p>\n","protected":false},"featured_media":4370,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":{"0":"post-4368","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-convencionales","7":"product_cat-equipos-de-corte-plasma","8":"product_cat-soldadura-y-corte","9":"yith_product_brand-bluweld","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/meriansrl.com\/home\/wp-json\/wp\/v2\/product\/4368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meriansrl.com\/home\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meriansrl.com\/home\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/meriansrl.com\/home\/wp-json\/wp\/v2\/comments?post=4368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meriansrl.com\/home\/wp-json\/wp\/v2\/media\/4370"}],"wp:attachment":[{"href":"https:\/\/meriansrl.com\/home\/wp-json\/wp\/v2\/media?parent=4368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}